{"id":50721,"date":"2026-07-15T08:43:47","date_gmt":"2026-07-15T08:43:47","guid":{"rendered":"https:\/\/www.vtmarkets.com\/fr-eu\/?p=50721"},"modified":"2026-07-15T08:43:50","modified_gmt":"2026-07-15T08:43:50","slug":"v2026071501","status":"publish","type":"post","link":"https:\/\/www.vtmarkets.com\/fr-eu\/dividend\/v2026071501\/","title":{"rendered":"Avis d&#8217;ajustement des dividendes &#8211; Jul 15 ,2026"},"content":{"rendered":"\n<p>\n    Cher Client,\n<\/p>\n<p>\n    Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &#038; Nom du produit &#038; Volume net\u201d.\n<\/p>\n<p>\n    Veuillez consulter le tableau ci-dessous pour plus de d\u00e9tails :\n<\/p>\n<p>\n    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vtmarkets.com\/fr-eu\/wp-content\/uploads\/sites\/19\/2026\/07\/email_fr2026071501.jpg\" alt=\"Avis d'ajustement des dividendes\" width=\"660\" height=\"587\">\n<\/p>\n<p>\n    Les donn\u00e9es ci-dessus sont fournies \u00e0 titre de r\u00e9f\u00e9rence uniquement, veuillez consulter le logiciel MT4\/MT5 pour des informations pr\u00e9cises.\n<\/p>\n<p>\n    Pour toute information compl\u00e9mentaire, n&#8217;h\u00e9sitez pas \u00e0 contacter  <a href=\"mailto:info@vtmarkets.com\">info@vtmarkets.com.<\/a>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cher Client, Veuillez noter que les dividendes des produits suivants seront ajust\u00e9s en cons\u00e9quence. Les dividendes des indices seront ex\u00e9cut\u00e9s s\u00e9par\u00e9ment via un relev\u00e9 de solde directement sur votre compte de trading, et le commentaire sera au format suivant : \u201cDiv &#038; Nom du produit &#038; Volume net\u201d. Veuillez consulter le tableau ci-dessous pour plus <a href=\"https:\/\/www.vtmarkets.com\/fr-eu\/dividend\/v2026071501\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-50721","post","type-post","status-publish","format-standard","hentry","category-dividend"],"acf":{"acf_article_selection_author":null},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/posts\/50721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/comments?post=50721"}],"version-history":[{"count":1,"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/posts\/50721\/revisions"}],"predecessor-version":[{"id":50723,"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/posts\/50721\/revisions\/50723"}],"wp:attachment":[{"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/media?parent=50721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/categories?post=50721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vtmarkets.com\/fr-eu\/wp-json\/wp\/v2\/tags?post=50721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}