{"id":51864,"date":"2026-07-15T08:50:19","date_gmt":"2026-07-15T08:50:19","guid":{"rendered":"https:\/\/www.vtmarkets.com\/es-latam\/?p=51864"},"modified":"2026-07-15T08:50:22","modified_gmt":"2026-07-15T08:50:22","slug":"v2026071501","status":"publish","type":"post","link":"https:\/\/www.vtmarkets.com\/es-latam\/dividend\/v2026071501\/","title":{"rendered":"Aviso de Ajuste de Dividendos &#8211; Jul 15 ,2026"},"content":{"rendered":"\n<p>\n    Estimado Cliente,\n<\/p>\n<p>\n    Tenga en cuenta que los dividendos de los siguientes productos se ajustar\u00e1n en consecuencia. Los dividendos de los \u00edndices se ejecutar\u00e1n por separado a trav\u00e9s de un extracto de saldo directamente en su cuenta de trading, y el comentario tendr\u00e1 el siguiente formato: \u201cDiv &#038; Nombre del Producto &#038; Volumen Neto\u201d.\n<\/p>\n<p>\n    Por favor, consulte la siguiente tabla para m\u00e1s detalles:\n<\/p>\n<p>\n    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.vtmarkets.com\/es-latam\/wp-content\/uploads\/sites\/25\/2026\/07\/email_es2026071501.jpg\" alt=\"Aviso de Ajuste de Dividendos\" width=\"660\" height=\"587\">\n<\/p>\n<p>\n    Los datos anteriores son solo de referencia; por favor, consulte el software MT4\/MT5 para obtener datos espec\u00edficos.\n<\/p>\n<p>\n    Si necesita m\u00e1s informaci\u00f3n, no dude en ponerse en contacto con <a href=\"mailto:info@vtmarkets.com\">info@vtmarkets.com.<\/a>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimado Cliente, Tenga en cuenta que los dividendos de los siguientes productos se ajustar\u00e1n en consecuencia. Los dividendos de los \u00edndices se ejecutar\u00e1n por separado a trav\u00e9s de un extracto de saldo directamente en su cuenta de trading, y el comentario tendr\u00e1 el siguiente formato: \u201cDiv &#038; Nombre del Producto &#038; Volumen Neto\u201d. Por favor, <a href=\"https:\/\/www.vtmarkets.com\/es-latam\/dividend\/v2026071501\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-51864","post","type-post","status-publish","format-standard","hentry","category-dividend"],"acf":{"acf_article_selection_author":null},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/posts\/51864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/comments?post=51864"}],"version-history":[{"count":1,"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/posts\/51864\/revisions"}],"predecessor-version":[{"id":51866,"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/posts\/51864\/revisions\/51866"}],"wp:attachment":[{"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/media?parent=51864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/categories?post=51864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vtmarkets.com\/es-latam\/wp-json\/wp\/v2\/tags?post=51864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}